{"id":33359,"date":"2018-03-30T11:54:05","date_gmt":"2018-03-30T17:54:05","guid":{"rendered":"http:\/\/snn.imer.gob.mx\/laferia\/?p=33359"},"modified":"2018-05-07T10:27:41","modified_gmt":"2018-05-07T16:27:41","slug":"criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes","status":"publish","type":"post","link":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/","title":{"rendered":"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes"},"content":{"rendered":"<p><a href=\"http:\/\/snn.imer.gob.mx\/laferia\/opera-lazaro\/\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-33357\" src=\"http:\/\/snn.imer.gob.mx\/laferia\/files\/2018\/03\/opera-Lazaro-300x110.jpg\" alt=\"\" width=\"300\" height=\"110\" srcset=\"https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro-300x110.jpg 300w, https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro-768x282.jpg 768w, https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro-1024x376.jpg 1024w, https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los retos que enfrenta la \u00d3pera de Bellas Artes son los\u00a0 recortes presupuestales y un trabajo delimitado, se\u00f1ala L\u00e1zaro Azar en la secci\u00f3n de cr\u00edticos.<\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-33359-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/snn.imer.gob.mx\/laferia\/files\/2018\/03\/CRITICO-LAZARO-AZAR1.mp3?_=1\" \/><a href=\"http:\/\/snn.imer.gob.mx\/laferia\/files\/2018\/03\/CRITICO-LAZARO-AZAR1.mp3\">http:\/\/snn.imer.gob.mx\/laferia\/files\/2018\/03\/CRITICO-LAZARO-AZAR1.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Los retos que enfrenta la \u00d3pera de Bellas Artes son los\u00a0 recortes presupuestales y un trabajo delimitado, se\u00f1ala L\u00e1zaro Azar en la secci\u00f3n de cr\u00edticos.<\/p>\n","protected":false},"author":12,"featured_media":33357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"wp_popup_display_lightbox":0,"wp_popup_suppress":"","wp_popup_trigger":"","wp_popup_trigger_amount":0,"wp_popup_disable_on_mobile":false},"categories":[1730],"tags":[3444,2186,5509],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural\" \/>\n<meta property=\"og:description\" content=\"Los retos que enfrenta la \u00d3pera de Bellas Artes son los\u00a0 recortes presupuestales y un trabajo delimitado, se\u00f1ala L\u00e1zaro Azar en la secci\u00f3n de cr\u00edticos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Feria, Carrusel Cultural\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-30T17:54:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-07T16:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Feria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Feria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/\",\"url\":\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/\",\"name\":\"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural\",\"isPartOf\":{\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/#website\"},\"datePublished\":\"2018-03-30T17:54:05+00:00\",\"dateModified\":\"2018-05-07T16:27:41+00:00\",\"author\":{\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/438ebaa433c79f71687928759130ec9f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticias.imer.mx\/laferia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/#website\",\"url\":\"https:\/\/noticias.imer.mx\/laferia\/\",\"name\":\"La Feria, Carrusel Cultural\",\"description\":\"Instituto Mexicano de la Radio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticias.imer.mx\/laferia\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/438ebaa433c79f71687928759130ec9f\",\"name\":\"La Feria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/69100f68fb4d3a06d1ff6b6cb5310157?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/69100f68fb4d3a06d1ff6b6cb5310157?s=96&d=mm&r=g\",\"caption\":\"La Feria\"},\"description\":\"La Feria Carrusel Cultural, es un noticiario que alienta la participaci\u00f3n ciudadana y presenta informaci\u00f3n cultural y cient\u00edfica, de coyuntura, de M\u00e9xico y el mundo. En media hora puede conocer la cartelera cultural y escuchar, en voz de especialistas, entrevistas, asuntos especiales y mesas de an\u00e1lisis. Conducido por Juan Carlos Vald\u00e9s, La Feria Carrusel Cultural, se transmite todos los martes y jueves, de 15:00 a 15:30 horas por Horizonte, en el 107.9 de FM.\",\"url\":\"https:\/\/noticias.imer.mx\/laferia\/author\/laferia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/","og_locale":"es_ES","og_type":"article","og_title":"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural","og_description":"Los retos que enfrenta la \u00d3pera de Bellas Artes son los\u00a0 recortes presupuestales y un trabajo delimitado, se\u00f1ala L\u00e1zaro Azar en la secci\u00f3n de cr\u00edticos.","og_url":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/","og_site_name":"La Feria, Carrusel Cultural","article_published_time":"2018-03-30T17:54:05+00:00","article_modified_time":"2018-05-07T16:27:41+00:00","og_image":[{"width":1280,"height":470,"url":"https:\/\/noticias.imer.mx\/laferia\/files\/2018\/03\/opera-Lazaro.jpg","type":"image\/jpeg"}],"author":"La Feria","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"La Feria"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/","url":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/","name":"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes - La Feria, Carrusel Cultural","isPartOf":{"@id":"https:\/\/noticias.imer.mx\/laferia\/#website"},"datePublished":"2018-03-30T17:54:05+00:00","dateModified":"2018-05-07T16:27:41+00:00","author":{"@id":"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/438ebaa433c79f71687928759130ec9f"},"breadcrumb":{"@id":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticias.imer.mx\/laferia\/2018\/03\/30\/criticos-lazaro-azar-habla-sobre-la-opera-de-bellas-artes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticias.imer.mx\/laferia\/"},{"@type":"ListItem","position":2,"name":"Cr\u00edtico: L\u00e1zaro Azar habla sobre la \u00d3pera de Bellas Artes"}]},{"@type":"WebSite","@id":"https:\/\/noticias.imer.mx\/laferia\/#website","url":"https:\/\/noticias.imer.mx\/laferia\/","name":"La Feria, Carrusel Cultural","description":"Instituto Mexicano de la Radio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.imer.mx\/laferia\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/438ebaa433c79f71687928759130ec9f","name":"La Feria","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.imer.mx\/laferia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/69100f68fb4d3a06d1ff6b6cb5310157?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69100f68fb4d3a06d1ff6b6cb5310157?s=96&d=mm&r=g","caption":"La Feria"},"description":"La Feria Carrusel Cultural, es un noticiario que alienta la participaci\u00f3n ciudadana y presenta informaci\u00f3n cultural y cient\u00edfica, de coyuntura, de M\u00e9xico y el mundo. En media hora puede conocer la cartelera cultural y escuchar, en voz de especialistas, entrevistas, asuntos especiales y mesas de an\u00e1lisis. Conducido por Juan Carlos Vald\u00e9s, La Feria Carrusel Cultural, se transmite todos los martes y jueves, de 15:00 a 15:30 horas por Horizonte, en el 107.9 de FM.","url":"https:\/\/noticias.imer.mx\/laferia\/author\/laferia\/"}]}},"_links":{"self":[{"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/posts\/33359"}],"collection":[{"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/comments?post=33359"}],"version-history":[{"count":2,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/posts\/33359\/revisions"}],"predecessor-version":[{"id":33607,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/posts\/33359\/revisions\/33607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/media\/33357"}],"wp:attachment":[{"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/media?parent=33359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/categories?post=33359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias.imer.mx\/laferia\/wp-json\/wp\/v2\/tags?post=33359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}